{"id":691,"date":"2012-02-11T20:26:07","date_gmt":"2012-02-11T20:26:07","guid":{"rendered":"https:\/\/masters.filescat.uab.cat\/webs\/portal\/master\/?p=691"},"modified":"2012-02-11T20:26:07","modified_gmt":"2012-02-11T20:26:07","slug":"enquesta-de-satisfaccio","status":"publish","type":"post","link":"https:\/\/masters.filescat.uab.cat\/moiellc\/enquesta-de-satisfaccio\/","title":{"rendered":"Enquesta de satisfacci\u00f3"},"content":{"rendered":"<h5 style=\"text-align: left\"><a href=\"http:\/\/pagines.uab.cat\/moiellc\/sites\/pagines.uab.cat.moiellc\/files\/formulari%20enquesta%20moiellc.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-693\" title=\"enquesta_g\" src=\"https:\/\/masters.filescat.uab.cat\/moiellc\/wp-content\/uploads\/sites\/4\/2012\/02\/enquesta_g.png\" alt=\"\" width=\"221\" height=\"210\" srcset=\"https:\/\/masters.filescat.uab.cat\/moiellc\/wp-content\/uploads\/sites\/4\/2012\/02\/enquesta_g.png 437w, https:\/\/masters.filescat.uab.cat\/moiellc\/wp-content\/uploads\/sites\/4\/2012\/02\/enquesta_g-300x285.png 300w\" sizes=\"(max-width: 221px) 100vw, 221px\" \/><\/a><br \/>\nSi ja heu finalitzat el M\u00e0ster Estudis Avan\u00e7ats de llengua i literatura catalanes, us agrair\u00edem que contest\u00e9ssiu l&#8217;<a href=\"http:\/\/pagines.uab.cat\/moiellc\/sites\/pagines.uab.cat.moiellc\/files\/formulari%20enquesta%20moiellc.pdf\" target=\"_blank\" rel=\"noopener\">enquesta de satisfacci\u00f3<\/a><\/h5>\n<blockquote>\n<div class=\"checklist checklist\">\n<ul>\n<li>Quan l&#8217;h\u00e0giu contestada feu-la arribar a l&#8217;adre\u00e7a del m\u00e0ster:<br \/>\n<a href=\"mailto:moiellc@uab.cat\"> moiellc@uab.cat<\/a><\/li>\n<\/ul>\n<\/div>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Si ja heu finalitzat el M\u00e0ster Estudis Avan\u00e7ats de llengua i literatura catalanes, us agrair\u00edem que contest\u00e9ssiu l&#8217;enquesta de satisfacci\u00f3 Quan l&#8217;h\u00e0giu contestada feu-la arribar a l&#8217;adre\u00e7a del m\u00e0ster: moiellc@uab.cat<\/p>\n","protected":false},"author":1,"featured_media":692,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[5],"tags":[15],"class_list":["post-691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-master","tag-enquesta","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/masters.filescat.uab.cat\/moiellc\/wp-json\/wp\/v2\/posts\/691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masters.filescat.uab.cat\/moiellc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/masters.filescat.uab.cat\/moiellc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/masters.filescat.uab.cat\/moiellc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/masters.filescat.uab.cat\/moiellc\/wp-json\/wp\/v2\/comments?post=691"}],"version-history":[{"count":0,"href":"https:\/\/masters.filescat.uab.cat\/moiellc\/wp-json\/wp\/v2\/posts\/691\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masters.filescat.uab.cat\/moiellc\/wp-json\/wp\/v2\/media\/692"}],"wp:attachment":[{"href":"https:\/\/masters.filescat.uab.cat\/moiellc\/wp-json\/wp\/v2\/media?parent=691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/masters.filescat.uab.cat\/moiellc\/wp-json\/wp\/v2\/categories?post=691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/masters.filescat.uab.cat\/moiellc\/wp-json\/wp\/v2\/tags?post=691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}